{"id":16134,"date":"2022-05-09T12:53:30","date_gmt":"2022-05-09T10:53:30","guid":{"rendered":"https:\/\/www.euroakademie.de\/magazin\/?p=16134"},"modified":"2024-12-04T10:26:53","modified_gmt":"2024-12-04T09:26:53","slug":"deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht","status":"publish","type":"post","link":"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/","title":{"rendered":"Deutsch-franz\u00f6sische Projektwoche in Vannes \u2013 ein Reisebericht"},"content":{"rendered":"<p><![CDATA[\n<\/p>\n\n\n<\/p>\n\n\n<p><strong>In der letzten Aprilwoche 2022 traten neun Sch\u00fcler*innen aus drei Klassen der Berufsfachschule f\u00fcr Pflegehilfe und der Berufsfachschule f\u00fcr Sozialwesen die Reise nach Vannes in Frankreich an. Schon viele Jahre nimmt die <a href=\"https:\/\/www.euroakademie.de\/standorte\/goerlitz.html\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Euro Akademie G\u00f6rlitz (\u00f6ffnet in neuem Tab)\">Euro Akademie G\u00f6rlitz<\/a> am deutsch-franz\u00f6sischen Sch\u00fcleraustausch teil. Das Projekt wird von Europa-Direkt e.V. organisiert und unterst\u00fctzt. Auf der Reise wurden die Sch\u00fcler*innen von Frau Lyseiko und Gerd Relitz, beides Fachlehrkr\u00e4fte an der Euro Akademie G\u00f6rlitz, begleitet. <\/strong><\/p>\n\n\n\n<p>Nachdem sich die Gruppe bereits im September 2021 mit den Sch\u00fcler*innen der Schule \u201eLyc\u00e9e Ker Anna\u201c aus Kervignac in Dresden zum Sch\u00fcleraustausch getroffen hatte, war es nun an der Zeit f\u00fcr den Gegenbesuch in der Bretagne. Dort wollten sie die Kultur und das Land kennenlernen, sich mit der franz\u00f6sischen Sprache vertraut machen und auch eine \u00f6rtliche Pflegeeinrichtung besuchen.<\/p>\n\n\n\n<p>Im Folgenden berichten sie \u00fcber den Aufenthalt, ihre Erfahrungen und die Unterschiede zum Arbeiten als Pflegekraft in Deutschland.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die Anreise <\/h2>\n\n\n\n<p>Die Reise begann bereits am Samstagabend mit der Zugfahrt und \u00dcbernachtung in Dresden, um am Sonntagmorgen auch sicher den ICE nach Frankfurt am Main zu schaffen. In Frankfurt traf sich die Reisegruppe mit ihrer Ansprechpartnerin und Teamerin von Europa-Direkt, Aline Massol, um zusammen weiter nach Paris zu reisen. Nach einer turbulenten Tour durch Paris, ging es im TGV weiter bis nach Vannes, wo der Himmel gerade seine letzten Regentropfen fallen lie\u00df. Nach einer kurzen Wanderung durch die Stadt bezogen alle ziemlich geschafft von der Reise ihre Zimmer im Espace Montcalm, wo sie dann auch die zweite Teamerin von Europa-Direkt, Anna Felsing, kennenlernten.\u2003<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Montag: Erste Sprachkenntnisse und F\u00fchrung durch das Pflegeheim<\/h2>\n\n\n\n<p>Gleich am Montag trafen wir uns, um \u00fcber die Wochenplanung und unsere Erwartungen zu sprechen. Nach dem wir die Regeln f\u00fcr die Gruppe festgelegt hatten, startete auch schon die erste Sprachanimation. Wir wiederholten die W\u00f6rter, die wir im September in Dresden schon gelernt hatten lernten neue Vokabeln durch Spiele kennen. Um uns in der fremden Stadt nicht zu verlaufen, lernten wir verschiedene Richtungsangaben, wie etwa \u201enach links\u201c \u2013 \u201e\u00e0 gauche\u201c, \u201erechts\u201c \u2013 \u201e\u00e0 droite\u201c oder \u201eimmer geradeaus\u201c \u2013 \u201etout droit\u201c. Mit einem kleinen Spielchen haben wir auch nochmal alle Namen gefestigt, da die Gruppe teilweise neue Mitglieder hatte. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Herzliche Begr\u00fc\u00dfung und viel Zeit<br><\/h3>\n\n\n\n<p>Nach einem leckeren Mittagessen besuchten wir ein Pflegeheim. Von Kenza, einer Mitarbeiterin der Einrichtung, die f\u00fcr die Freizeitgestaltung der Bewohner*innen zust\u00e4ndig ist, bekamen wir eine F\u00fchrung. Sie zeigte uns das ganze Geb\u00e4ude und kl\u00e4rte uns \u00fcber die verschiedenen Aufgaben und die Technik in der Einrichtung auf. Schon da bemerkten wir viele Unterschiede zwischen Frankreich und Deutschland, weshalb die F\u00fchrung sehr spannend f\u00fcr uns war. Besonders auff\u00e4llig war, wie famili\u00e4r die Einrichtung gestaltet ist und wie viel Zeit die Mitarbeiter*innen sich f\u00fcr die Bewohner*innen nehmen konnten. W\u00e4hrend der F\u00fchrung lernten wir auch schon einige Senior*innen kennen, die teilweise sogar Deutsch konnten und uns sehr herzlich behandelt und begr\u00fc\u00dft haben. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Stadtrallye mit W\u00f6rtersuche  <\/h3>\n\n\n\n<p>Nach der F\u00fchrung gab es eine Stadtrallye. Bei der Rallye sollten wir verschiedene Sehensw\u00fcrdigkeiten in Vannes besuchen und fotografieren, au\u00dferdem sollten wir Internationalismen finden, also W\u00f6rter, die im Deutschen gleich oder \u00e4hnlich wie im Franz\u00f6sischen geschrieben werden. Hier fanden wir zum Beispiel die W\u00f6rter \u201eStop\u201c, \u201eTaxi\u201c oder \u201eZone\u201c. Au\u00dferdem hatten wir die Aufgabe, etwas Dreifarbiges zu suchen und ein typisches Lebensmittel finden wie zum Beispiel das salzige Karamell. <\/p>\n\n\n\n<p>Als wir zur\u00fcckkamen, haben wir alles ausgewertet und danach gab es Abendessen, welches allen auch sehr gut geschmeckt hat. Insgesamt war es ein sehr sch\u00f6ner Tag mit sehr vielen neuen Eindr\u00fccken und Erfahrungen. <em>Text: Violet (SOA20b) und Lena (KPH21)\u2003 <\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dienstag: Treffen mit franz\u00f6sischen Sch\u00fcler*innen<\/h2>\n\n\n\n<p>Der Dienstag begann mit gro\u00dfer Vorfreude darauf, die franz\u00f6sischen Sch\u00fcler*innen und Lehrkr\u00e4fte wiederzusehen. Nach dem Fr\u00fchst\u00fcck ging es noch in die letzten Vorbereitungen, bevor wir uns gegen 10 Uhr zu einem gemeinsamen Empfang in unserem Gruppenraum mit den Sch\u00fcler*innen aus Kervignac zusammenfanden. Sprachaktivit\u00e4ten in spielerischer Form, welche drinnen und drau\u00dfen stattfanden, waren ein guter Einstieg in den Tag, bevor wir uns f\u00fcr ein Mittagessen selbstst\u00e4ndig in die Stadt begaben.<\/p>\n\n\n\n<p>Dort sa\u00dfen wir dann \u00fcberwiegend am Hafen und tauschten uns bestm\u00f6glich aus. Anschlie\u00dfend ging es wieder in die Herberge, wo die Franz\u00f6sinnen einen Vortrag \u00fcber die Bretagne hielten, bevor sie uns ein Buffet mit lokalen Spezialit\u00e4ten pr\u00e4sentierten. Wir konnten unter anderem Cr\u00eapes mit gesalzenem Karamell probieren, wie auch typisches Geb\u00e4ck und S\u00fc\u00dfigkeiten. <\/p>\n\n\n\n<p>Nach dieser umfangreichen Verk\u00f6stigung mussten wir uns von unseren Freund*innen allerdings wieder verabschieden, da sich diese gerade in einer intensiven Pr\u00fcfungsphase befinden. Mit einem kleinen Gastgeschenk von uns im Gep\u00e4ck machten sie sich also wieder auf den Heimweg. Den Nachmittag lie\u00dfen wir in Freizeit ausklingen, die \u00fcberwiegend f\u00fcr die Erkundung von Vannes genutzt wurde. Daraufhin trafen wir uns nochmal zum Abendessen und ein langer und sonniger Tag ging damit zu Ende.  <br><em>Text: Niklas (KPH21), Tony und Julius (SOA20b) \u2003<\/em> <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"375\" data-id=\"16142\" src=\"https:\/\/relaunch.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220425_103543_web.jpg\" alt=\"\" class=\"wp-image-16142\" srcset=\"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220425_103543_web.jpg 500w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220425_103543_web-300x225.jpg 300w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220425_103543_web-150x113.jpg 150w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220425_103543_web-450x338.jpg 450w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"500\" height=\"353\" data-id=\"16143\" src=\"https:\/\/relaunch.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220425_151735_web.jpg\" alt=\"\" class=\"wp-image-16143\" srcset=\"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220425_151735_web.jpg 500w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220425_151735_web-300x212.jpg 300w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220425_151735_web-150x106.jpg 150w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220425_151735_web-450x318.jpg 450w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"500\" height=\"333\" data-id=\"16144\" src=\"https:\/\/relaunch.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220425_181522_web.jpg\" alt=\"\" class=\"wp-image-16144\" srcset=\"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220425_181522_web.jpg 500w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220425_181522_web-300x200.jpg 300w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220425_181522_web-150x100.jpg 150w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220425_181522_web-450x300.jpg 450w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"357\" data-id=\"16145\" src=\"https:\/\/relaunch.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220429_093028-web.jpg\" alt=\"\" class=\"wp-image-16145\" srcset=\"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220429_093028-web.jpg 500w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220429_093028-web-300x214.jpg 300w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220429_093028-web-150x107.jpg 150w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG_20220429_093028-web-450x321.jpg 450w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"424\" data-id=\"16146\" src=\"https:\/\/relaunch.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0047_web.jpg\" alt=\"\" class=\"wp-image-16146\" srcset=\"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0047_web.jpg 500w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0047_web-300x254.jpg 300w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0047_web-150x127.jpg 150w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0047_web-450x382.jpg 450w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"328\" data-id=\"16155\" src=\"https:\/\/relaunch.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0054_web.jpg\" alt=\"\" class=\"wp-image-16155\" srcset=\"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0054_web.jpg 500w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0054_web-300x197.jpg 300w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0054_web-150x98.jpg 150w, https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0054_web-450x295.jpg 450w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Mittwoch: Unser Ausflug zur \u00eele d\u00b4Arz <\/h2>\n\n\n\n<p>Nach unserem gemeinsamen Fr\u00fchst\u00fcck begann unser Programm um 9:30 Uhr. Die beiden Gruppenbetreuerinnen Aline und Anna hatten ein paar lustige Spiele zur Sprachanimation vorbereitet. Passend zum heutigen Ausflug konnten wir einige neue Vokabeln lernen zum Beispiel: bateau (Schiff), \u00eele (Insel), mar\u00e9e haute (Flut), mar\u00e9e basse (Ebbe) und mouette (M\u00f6we). Nach der kleinen Aufw\u00e4rmrunde packten wir unsere Lunch-Pakete ein und gingen zur Haltestelle Le Port, um mit dem Bus nach Parc du Golfe zu fahren, dort stiegen wir auf die F\u00e4hre nach \u00eele d\u00b4Arz.  <\/p>\n\n\n\n<p>Auf der Insel angelangt, fiel uns der niedrige Wasserstand auf. Es war gerade Ebbe und wir konnten weit ins Watt hineingehen. Hier gab es einiges Interessantes zu entdecken. Einige fanden verschiedene Muscheln, Krebse, Wasserpflanzen oder sogar gr\u00f6\u00dfere Meerestiere. Wir folgten dem Weg am Strand entlang und fanden viele M\u00f6glichkeiten, um sch\u00f6ne Erinnerungsfotos zu machen. Unser Weg f\u00fchrte uns sogar an einen See auf der Insel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Inselerkundung \u2013 Steinh\u00e4user und bunte Fensterl\u00e4den <\/h3>\n\n\n\n<p>An der K\u00fcste fanden wir einen Tisch, hier haben wir gemeinsam unser Lunch-Paket gegessen und eine Rast gemacht. Nach unserer Pause gelangten wir in die Stadt der Insel. Besonders auff\u00e4llig waren die typischen Steinh\u00e4user mit bunten Fensterl\u00e4den und die hohen Steinmauern mit wildwachsenden Blumen und Str\u00e4uchern. In der Stadt konnten wir etwas Zeit f\u00fcr uns selbst nutzen, um die Gegend eigenst\u00e4ndig zu erkunden. <\/p>\n\n\n\n<p>Danach folgten wir dem Weg quer durch die Stadt Richtung Hafen. Ein gemeinsames Gruppen-Selfie durfte nat\u00fcrlich auch nicht fehlen, danach gingen wir weiter entlang der K\u00fcste. Wir machten eine letzte Rast am Strand, hier bemerkten wir, dass das Wasser wieder deutlich gestiegen war und die Flut kam.  Wieder am Hafen angelangt, fuhren wir mit der F\u00e4hre wieder aufs Festland zur\u00fcck. <\/p>\n\n\n\n<p>In Vannes hatten wir den restlichen Tag Freizeit. Einige nutzen die Zeit, um regionale Speisen zu kaufen oder das eine oder andere Mitbringsel zu besorgen. Unsere Gruppe traf sich p\u00fcnktlich um 19:30 Uhr wieder zum gemeinsamen Abendessen. Zusammenfassend k\u00f6nnen wir nur best\u00e4tigen, dass es ein besonders sch\u00f6ner Ausflug f\u00fcr uns alle war und dass wir mit neuen Erfahrungen, Franz\u00f6sisch-Vokabeln und einigen Sonnenbr\u00e4nden zur\u00fcckgekehrt sind.  <br><em>Text: Emma und Jinhua (SOA 20a)\u2003 <\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Donnerstag: Angebot im Pflegeheim <\/h2>\n\n\n\n<p>Am Morgen haben wir, wie jeden Tag nach dem Fr\u00fchst\u00fcck, \u00fcber die Tagesplanung geredet. Nach ein paar Spielen zur Sprachanimation haben wir uns in drei Gruppen aufgeteilt und \u00fcberlegt, welche Aktivit\u00e4ten wir den Bewohner*innen des Pflegeheims vorstellen, bei denen sie sich nat\u00fcrlich auch beteiligen k\u00f6nnen. Emma &amp; Tony haben sich Fragen an die Fachkr\u00e4fte im Pflegeheim und auch an die Bewohner*innen \u00fcberlegt. <\/p>\n\n\n\n<p>Julius, Niklas &amp; Jinhua suchten Sprichw\u00f6rter und Redewendungen auf Deutsch heraus, f\u00fcr die es auch im Franz\u00f6sischen Redewendungen mit der gleichen Bedeutung gibt. Die dritte Gruppe, Gerd Relitz, Violet und wir (Souad &amp; Lea), \u00fcberlegten, dass ein Lied mit erg\u00e4nzenden Bewegungen dazu eine sch\u00f6ne Idee w\u00e4re. Wir suchten ein Lied, das es sowohl im Franz\u00f6sischen als auch im Deutschen gibt. Wir fanden das Kinderlied &#8222;Kopf, Schultern, Knie &amp; Fu\u00df&#8220; oder auch auf Franz\u00f6sisch &#8222;T\u00eate, \u00e9paules, genoux et pieds&#8220;. <\/p>\n\n\n\n<p>Nach ein wenig \u00dcbung waren wir f\u00fcr den Nachmittag gut vorbereitet. Reger Austausch mit Mitarbeitenden im Pflegeheim Anschlie\u00dfend fuhren wir mit dem Bus zum Altenheim. Dort nahmen sich die Mitarbeiter*innen extra w\u00e4hrend ihrer Pause Zeit f\u00fcr uns. Tony und Emma konnten so in Ruhe ihre Fragen stellen. Es ergab sich ein reger Austausch, denn auch die Fachkr\u00e4fte im Pflegeheim waren sehr daran interessiert, welche Erfahrungen wir in unseren Praktika machen konnten. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Alle machten mit <\/h3>\n\n\n\n<p>Im Anschluss haben wir dann alle unsere Aktivit\u00e4ten den Bewohner*innen vorgestellt. Was uns alle positiv \u00fcberraschte war, dass sich alle Anwesenden wirklich aktiv beteiligten und sehr gut dabei waren. Sie haben das Lied mitgesungen, die Bewegungen mitgemacht und alle Redewendungen erraten. Es war eine sehr sch\u00f6ne Atmosph\u00e4re und im Anschluss konnten wir auch ein bisschen mit den Bewohner*innen ins Gespr\u00e4ch kommen.<\/p>\n\n\n\n<p>Danach sind wir dann zur Herberge zur\u00fcckgelaufen und haben den Tag und die gesamte Projektwoche ausgewertet. Uns blieb dann noch ein wenig Freizeit und diese nutzten wir, um zu packen oder noch einmal in die Stadt zu gehen. Nach dem Abendessen hatten wir noch eine kleine \u201eAbschlussfeier\u201c, bei wir auch \u201eWerwolf\u201c gespielt haben. <br> <em>Text: Souad und Lea (KPH 21)<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Freitag: die R\u00fcckreise<\/h2>\n\n\n\n<p>Noch vor dem Sonnenaufgang ging der Sch\u00fcleraustausch zu Ende und die Gruppe aus G\u00f6rlitz musste sich wieder auf den Heimweg begeben. Ein letztes Mal wanderten die Sch\u00fcler*innen durch Vannes um den TGV nach Paris um 6:30 Uhr zu erreichen. Die Heimfahrt war gerade in Paris deutlich entspannter und schon w\u00e4hrend der R\u00fcckfahrt wurden Geschichten und Erlebnisse aus dem Sch\u00fcleraustausch in Vannes besprochen. <\/p>\n\n\n\n<p>Gerade der Besuch im Pflegeheim und die Zeit gemeinsam mit der franz\u00f6sischen Gruppe aus Kervignac wird vielen wohl noch lange in Erinnerung bleiben. Und wie bei jeder guten Reise waren sich fast alle einig: Wir h\u00e4tten gerne noch ein bisschen l\u00e4nger in Vannes bleiben k\u00f6nnen. Au revoir, Frankreich!<br><em>Text: Gerd Relitz<\/em><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size has-regular-font-size\"><a class=\"wp-block-button__link has-white-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.euroakademie.de\/goerlitz\" style=\"background-color:#00305d;padding-top:var(--wp--preset--spacing--30);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--20)\"> Sie interessieren sich f\u00fcr eine Ausbildung im Bereich Gesundheit &amp;  Pflege oder P\u00e4dagogik &amp; Soziales an der Euro Akademie G\u00f6rlitz?  St\u00f6bern Sie doch gleich mal in den Ausbildungsangeboten.   <\/a><\/div>\n<\/div>\n\n\n\n<p><br><em>Bildquelle: Euro Akademie G\u00f6rlitz (privat)<\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\t\t\t\t<![CDATA[Neun Sch\u00fcler*innen der Euro Akademie G\u00f6rlitz waren auf einem Sch\u00fcleraustausch in Frankreich. Dort lernten sie die Sprache und stellten einige Unterschiede zur Arbeit in deutschen Pflegeeinrichtungen fest. ]]>\t\t<\/p>\n","protected":false},"author":25,"featured_media":16139,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,103,118],"tags":[928,2014,3118,3121,3715,6433],"class_list":{"0":"post-16134","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-gesundheit-pflege","8":"category-goerlitz","9":"category-im-fokus","10":"tag-auslandsaufenthalt","11":"tag-deutsch-franzoesischer-austausch","12":"tag-frankreich","13":"tag-franzoesisch","14":"tag-goerlitz","15":"tag-pflegekraefte"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Deutsch-franz\u00f6sische Projektwoche in Vannes \/ Euro Akademie Magazin<\/title>\n<meta name=\"description\" content=\"Angehende Pflegekr\u00e4fte der Euro Akademie G\u00f6rlitz nahmen am Deutsch-franz\u00f6sischen Austauschprogramm in Vannes teil.Hier berichten sie \u00fcber ihre Erfahrungen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deutsch-franz\u00f6sische Projektwoche in Vannes \/ Euro Akademie Magazin\" \/>\n<meta property=\"og:description\" content=\"Angehende Pflegekr\u00e4fte der Euro Akademie G\u00f6rlitz nahmen am Deutsch-franz\u00f6sischen Austauschprogramm in Vannes teil.Hier berichten sie \u00fcber ihre Erfahrungen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/\" \/>\n<meta property=\"og:site_name\" content=\"Das Euro Akademie Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-09T10:53:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-04T09:26:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0049_702x336.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"702\" \/>\n\t<meta property=\"og:image:height\" content=\"336\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sch\u00fcler*innen der Euro Akademie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sch\u00fcler*innen der Euro Akademie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/\"},\"author\":{\"name\":\"Sch\u00fcler*innen der Euro Akademie\",\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/#\/schema\/person\/88061163260e860aeebdcfa336a1a0d7\"},\"headline\":\"Deutsch-franz\u00f6sische Projektwoche in Vannes \u2013 ein Reisebericht\",\"datePublished\":\"2022-05-09T10:53:30+00:00\",\"dateModified\":\"2024-12-04T09:26:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/\"},\"wordCount\":1780,\"publisher\":{\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0049_702x336.jpg\",\"keywords\":[\"Auslandsaufenthalt\",\"deutsch-franz\u00f6sischer Austausch\",\"Frankreich\",\"franz\u00f6sisch\",\"G\u00f6rlitz\",\"Pflegekr\u00e4fte\"],\"articleSection\":[\"Gesundheit &amp; Pflege\",\"G\u00f6rlitz\",\"Im Fokus\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/\",\"url\":\"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/\",\"name\":\"Deutsch-franz\u00f6sische Projektwoche in Vannes \/ Euro Akademie Magazin\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0049_702x336.jpg\",\"datePublished\":\"2022-05-09T10:53:30+00:00\",\"dateModified\":\"2024-12-04T09:26:53+00:00\",\"description\":\"Angehende Pflegekr\u00e4fte der Euro Akademie G\u00f6rlitz nahmen am Deutsch-franz\u00f6sischen Austauschprogramm in Vannes teil.Hier berichten sie \u00fcber ihre Erfahrungen.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/#primaryimage\",\"url\":\"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0049_702x336.jpg\",\"contentUrl\":\"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0049_702x336.jpg\",\"width\":702,\"height\":336,\"caption\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.euroakademie.de\/magazin\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deutsch-franz\u00f6sische Projektwoche in Vannes \u2013 ein Reisebericht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/#website\",\"url\":\"https:\/\/www.euroakademie.de\/magazin\/\",\"name\":\"Das Euro Akademie Magazin\",\"description\":\"Gut informiert durch Ausbildung und Studium\",\"publisher\":{\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroakademie.de\/magazin\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/#organization\",\"name\":\"ESO Education Group\",\"url\":\"https:\/\/www.euroakademie.de\/magazin\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/relaunch.euroakademie.de\/magazin\/wp-content\/uploads\/2024\/11\/Logo_EA_negativ_Rahmen_5cm_300dpi_RGB.jpg\",\"contentUrl\":\"https:\/\/relaunch.euroakademie.de\/magazin\/wp-content\/uploads\/2024\/11\/Logo_EA_negativ_Rahmen_5cm_300dpi_RGB.jpg\",\"width\":591,\"height\":236,\"caption\":\"ESO Education Group\"},\"image\":{\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroakademie.de\/magazin\/#\/schema\/person\/88061163260e860aeebdcfa336a1a0d7\",\"name\":\"Sch\u00fcler*innen der Euro Akademie\",\"description\":\"Unter diesem Autorennamen schildern Sch\u00fcler*innen der Euro Akademien ihre pers\u00f6nlichen Erfahrungen zum Thema Ausbildung, berichten \u00fcber Projekte, Praktika oder Veranstaltungen und geben anderen Lernenden wertvolle Tipps. Sie gehen dabei auf Fragen ein, auf die sie vor und in ihrer Ausbildungszeit selbst gern Antworten gehabt h\u00e4tten.\",\"url\":\"https:\/\/www.euroakademie.de\/magazin\/author\/schueler\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deutsch-franz\u00f6sische Projektwoche in Vannes \/ Euro Akademie Magazin","description":"Angehende Pflegekr\u00e4fte der Euro Akademie G\u00f6rlitz nahmen am Deutsch-franz\u00f6sischen Austauschprogramm in Vannes teil.Hier berichten sie \u00fcber ihre Erfahrungen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/","og_locale":"de_DE","og_type":"article","og_title":"Deutsch-franz\u00f6sische Projektwoche in Vannes \/ Euro Akademie Magazin","og_description":"Angehende Pflegekr\u00e4fte der Euro Akademie G\u00f6rlitz nahmen am Deutsch-franz\u00f6sischen Austauschprogramm in Vannes teil.Hier berichten sie \u00fcber ihre Erfahrungen.","og_url":"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/","og_site_name":"Das Euro Akademie Magazin","article_published_time":"2022-05-09T10:53:30+00:00","article_modified_time":"2024-12-04T09:26:53+00:00","og_image":[{"width":702,"height":336,"url":"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0049_702x336.jpg","type":"image\/jpeg"}],"author":"Sch\u00fcler*innen der Euro Akademie","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Sch\u00fcler*innen der Euro Akademie","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/#article","isPartOf":{"@id":"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/"},"author":{"name":"Sch\u00fcler*innen der Euro Akademie","@id":"https:\/\/www.euroakademie.de\/magazin\/#\/schema\/person\/88061163260e860aeebdcfa336a1a0d7"},"headline":"Deutsch-franz\u00f6sische Projektwoche in Vannes \u2013 ein Reisebericht","datePublished":"2022-05-09T10:53:30+00:00","dateModified":"2024-12-04T09:26:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/"},"wordCount":1780,"publisher":{"@id":"https:\/\/www.euroakademie.de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0049_702x336.jpg","keywords":["Auslandsaufenthalt","deutsch-franz\u00f6sischer Austausch","Frankreich","franz\u00f6sisch","G\u00f6rlitz","Pflegekr\u00e4fte"],"articleSection":["Gesundheit &amp; Pflege","G\u00f6rlitz","Im Fokus"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/","url":"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/","name":"Deutsch-franz\u00f6sische Projektwoche in Vannes \/ Euro Akademie Magazin","isPartOf":{"@id":"https:\/\/www.euroakademie.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/#primaryimage"},"image":{"@id":"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0049_702x336.jpg","datePublished":"2022-05-09T10:53:30+00:00","dateModified":"2024-12-04T09:26:53+00:00","description":"Angehende Pflegekr\u00e4fte der Euro Akademie G\u00f6rlitz nahmen am Deutsch-franz\u00f6sischen Austauschprogramm in Vannes teil.Hier berichten sie \u00fcber ihre Erfahrungen.","breadcrumb":{"@id":"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/#primaryimage","url":"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0049_702x336.jpg","contentUrl":"https:\/\/www.euroakademie.de\/magazin\/wp-content\/uploads\/2022\/05\/IMG-20220429-WA0049_702x336.jpg","width":702,"height":336,"caption":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroakademie.de\/magazin\/deutsch-franzoesische-projektwoche-in-vannes-ein-reisebericht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.euroakademie.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Deutsch-franz\u00f6sische Projektwoche in Vannes \u2013 ein Reisebericht"}]},{"@type":"WebSite","@id":"https:\/\/www.euroakademie.de\/magazin\/#website","url":"https:\/\/www.euroakademie.de\/magazin\/","name":"Das Euro Akademie Magazin","description":"Gut informiert durch Ausbildung und Studium","publisher":{"@id":"https:\/\/www.euroakademie.de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroakademie.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.euroakademie.de\/magazin\/#organization","name":"ESO Education Group","url":"https:\/\/www.euroakademie.de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.euroakademie.de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/relaunch.euroakademie.de\/magazin\/wp-content\/uploads\/2024\/11\/Logo_EA_negativ_Rahmen_5cm_300dpi_RGB.jpg","contentUrl":"https:\/\/relaunch.euroakademie.de\/magazin\/wp-content\/uploads\/2024\/11\/Logo_EA_negativ_Rahmen_5cm_300dpi_RGB.jpg","width":591,"height":236,"caption":"ESO Education Group"},"image":{"@id":"https:\/\/www.euroakademie.de\/magazin\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.euroakademie.de\/magazin\/#\/schema\/person\/88061163260e860aeebdcfa336a1a0d7","name":"Sch\u00fcler*innen der Euro Akademie","description":"Unter diesem Autorennamen schildern Sch\u00fcler*innen der Euro Akademien ihre pers\u00f6nlichen Erfahrungen zum Thema Ausbildung, berichten \u00fcber Projekte, Praktika oder Veranstaltungen und geben anderen Lernenden wertvolle Tipps. Sie gehen dabei auf Fragen ein, auf die sie vor und in ihrer Ausbildungszeit selbst gern Antworten gehabt h\u00e4tten.","url":"https:\/\/www.euroakademie.de\/magazin\/author\/schueler\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroakademie.de\/magazin\/wp-json\/wp\/v2\/posts\/16134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroakademie.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroakademie.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroakademie.de\/magazin\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroakademie.de\/magazin\/wp-json\/wp\/v2\/comments?post=16134"}],"version-history":[{"count":4,"href":"https:\/\/www.euroakademie.de\/magazin\/wp-json\/wp\/v2\/posts\/16134\/revisions"}],"predecessor-version":[{"id":25284,"href":"https:\/\/www.euroakademie.de\/magazin\/wp-json\/wp\/v2\/posts\/16134\/revisions\/25284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euroakademie.de\/magazin\/wp-json\/wp\/v2\/media\/16139"}],"wp:attachment":[{"href":"https:\/\/www.euroakademie.de\/magazin\/wp-json\/wp\/v2\/media?parent=16134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroakademie.de\/magazin\/wp-json\/wp\/v2\/categories?post=16134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroakademie.de\/magazin\/wp-json\/wp\/v2\/tags?post=16134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}